{"id":35,"count":6,"description":"","link":"http:\/\/www.element-restaurant.com\/blog\/tag\/new-years-eve\/","name":"new years eve","slug":"new-years-eve","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.element-restaurant.com\/blog\/wp-json\/wp\/v2\/tags\/35"}],"collection":[{"href":"http:\/\/www.element-restaurant.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.element-restaurant.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.element-restaurant.com\/blog\/wp-json\/wp\/v2\/posts?tags=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}